{"id":6925,"date":"2026-01-15T14:32:00","date_gmt":"2026-01-15T14:32:00","guid":{"rendered":"https:\/\/psicoresiliencia.com\/?page_id=6925"},"modified":"2026-01-15T14:33:52","modified_gmt":"2026-01-15T14:33:52","slug":"politica-de-cookies-eni","status":"publish","type":"page","link":"https:\/\/psicoresiliencia.com\/index.php\/psicoterapia-online\/politica-de-cookies-eni\/","title":{"rendered":"Pol\u00edtica de Cookies ENI"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6925\" class=\"elementor elementor-6925\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6fc26a e-con-full e-flex e-con e-parent\" data-id=\"a6fc26a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;pyramids&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M761.9,44.1L643.1,27.2L333.8,98L0,3.8V0l1000,0v3.9\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1408389 e-con-full e-flex e-con e-child\" data-id=\"1408389\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40eeb9e elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-widget elementor-widget-heading\" data-id=\"40eeb9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de cookies<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-415c175 e-flex e-con-boxed e-con e-parent\" data-id=\"415c175\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee48220 elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-widget-tablet_extra__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ee48220\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este Website pertence a&nbsp;<b><span style=\"font-size:11.0pt;line-height:107%;font-family:&quot;Calibri&quot;,sans-serif;\nmso-ascii-theme-font:minor-latin;mso-fareast-font-family:Calibri;mso-fareast-theme-font:\nminor-latin;mso-hansi-theme-font:minor-latin;mso-bidi-font-family:&quot;Times New Roman&quot;;\nmso-bidi-theme-font:minor-bidi;mso-ansi-language:PT;mso-fareast-language:EN-US;\nmso-bidi-language:AR-SA\">Patr\u00edcia Machado Francisco, empres\u00e1ria em nome\nindividual, com o NIF: 211&nbsp;607&nbsp;037, adiante designada por\nPsicoresili\u00eancia<\/span><\/b><strong>ia. <\/strong>De seguida ser\u00e1 descrita a nossa <strong>pol\u00edtica de cookies:<\/strong><\/p>\n<p><strong>&nbsp;<br><\/strong>A<strong> Psicoresili\u00eancia. <\/strong>utiliza cookies de sess\u00e3o, que s\u00e3o pequenos ficheiros informativos enviados do servidor do website para o browser do utilizador e armazenado no respetivo computador. Trata-se de cookies tempor\u00e1rios que permanecem no arquivo de cookies apenas durante a utiliza\u00e7\u00e3o do website. Estes cookies ser\u00e3o utilizados exclusivamente pela <strong>Psicoresili\u00eancia <\/strong>e a sua utiliza\u00e7\u00e3o servir\u00e1 apenas para analisar padr\u00f5es de tr\u00e1fego na web, permitindo identificar problemas e fornecer uma melhor experi\u00eancia de navega\u00e7\u00e3o.<\/p>\n<p>Utilizamos cookies neste website. Um cookie \u00e9 um pequeno arquivo de texto que identifica o seu computador no nosso servidor. Os cookies em si n\u00e3o identificam o utilizador individual, apenas o computador utilizado. Os cookies n\u00e3o s\u00e3o usados para recolher informa\u00e7\u00f5es pessoais.<\/p>\n<p>Este website utiliza cookies que servem para ajudar a determinar a utilidade, interesse e o n\u00famero de acessos ao website, permitindo uma navega\u00e7\u00e3o mais r\u00e1pida e eficiente do mesmo, eliminando a necessidade de introduzir repetidamente as mesmas informa\u00e7\u00f5es.<\/p>\n<p>A utiliza\u00e7\u00e3o de cookies por este s\u00edtio pressupor\u00e1 sempre o seu pr\u00e9vio consentimento.<\/p>\n<p><strong>Os cookies que utilizamos:<\/strong><\/p>\n<p><strong>Cookies anal\u00edticos<\/strong> que s\u00e3o usados para entender como os visitantes interagem com o site. Esses cookies ajudam a fornecer informa\u00e7\u00f5es sobre as m\u00e9tricas do n\u00famero de visitantes, taxa de rejei\u00e7\u00e3o, origem do tr\u00e1fego, etc.<\/p>\n<p>Os <strong>cookies funcionais<\/strong> que ajudam a realizar certas funcionalidades, como compartilhar o conte\u00fado do site em plataformas de m\u00eddia social, coletar feedbacks e outros recursos de terceiros.<\/p>\n<p>Todos os browsers permitem ao Utilizador aceitar, recusar ou apagar cookies, nomeadamente atrav\u00e9s da sele\u00e7\u00e3o das defini\u00e7\u00f5es apropriadas no respetivo navegador. Pode configurar os cookies no menu &#8220;configura\u00e7\u00f5es&#8221; ou &#8220;prefer\u00eancias&#8221; do seu browser. Para saber mais sobre os cookies, incluindo a forma de ver o que os cookies foram criados e como gerenciar e exclu\u00ed-los, visite www.allaboutcookies.org que inclui informa\u00e7\u00f5es sobre como gerir as suas configura\u00e7\u00f5es para os v\u00e1rios fornecedores de navegadores.<br>Note-se, no entanto, que, ao desativar cookies, pode afetar, parcial ou totalmente, a sua experi\u00eancia de navega\u00e7\u00e3o no website.<\/p>\n<p><strong>Contactos e Esclarecimento de d\u00favidas <\/strong><\/p>\n<p>Em caso de d\u00favida sobre os pontos aqui apresentados, poder\u00e1 contactar-nos atrav\u00e9s de e-mail: <a href=\"mailto:geral@psicoresiliencia.com\">geral@psicoresiliencia.com<\/a><\/p>\n<p><strong>Altera\u00e7\u00f5es a esta Pol\u00edtica de Cookies<\/strong><strong>&nbsp;<\/strong><\/p>\n<p>As nossas pol\u00edticas de cookies s\u00e3o revistas regularmente e todas as altera\u00e7\u00f5es ser\u00e3o publicadas neste website. A \u00faltima atualiza\u00e7\u00e3o \u00e9 de 17 de outubro de 2025.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de cookies Este Website pertence a&nbsp;Patr\u00edcia Machado Francisco, empres\u00e1ria em nome individual, com o NIF: 211&nbsp;607&nbsp;037, adiante designada por Psicoresili\u00eanciaia. De seguida ser\u00e1 descrita a nossa pol\u00edtica de cookies: &nbsp;A Psicoresili\u00eancia. utiliza cookies de sess\u00e3o, que s\u00e3o pequenos ficheiros informativos enviados do servidor do website para o browser do utilizador e armazenado no respetivo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":359,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6925","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/pages\/6925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/comments?post=6925"}],"version-history":[{"count":0,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/pages\/6925\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/pages\/359"}],"wp:attachment":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/media?parent=6925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}