{"id":5139,"date":"2024-07-03T08:36:19","date_gmt":"2024-07-03T08:36:19","guid":{"rendered":"https:\/\/psicoresiliencia.com\/?p=5139"},"modified":"2024-11-08T11:42:19","modified_gmt":"2024-11-08T11:42:19","slug":"ansiedade-vs-perturbacao-de-ansiedade","status":"publish","type":"post","link":"https:\/\/psicoresiliencia.com\/index.php\/2024\/07\/03\/ansiedade-vs-perturbacao-de-ansiedade\/","title":{"rendered":"Perturba\u00e7\u00e3o de Ansiedade vs Ansiedade"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5139\" class=\"elementor elementor-5139\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c27ba2e e-flex e-con-boxed e-con e-parent\" data-id=\"c27ba2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-267d106 elementor-widget elementor-widget-text-editor\" data-id=\"267d106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9 mais f\u00e1cil compreendermos a ansiedade analisando o que \u00e9 ansiedade e o que n\u00e3o \u00e9 ansiedade. Por exemplo, \u00e9 poss\u00edvel diferenciar a ansiedade do medo de diversas formas. Quando est\u00e1 com medo, esse medo \u00e9 normalmente dirigido a algo concreto, seja um objeto ou situa\u00e7\u00e3o. Contudo, em situa\u00e7\u00f5es de ansiedade muitas vezes n\u00e3o se consegue identificar ao certo em rela\u00e7\u00e3o a que \u00e9 que se est\u00e1 ansioso. O foco da ansiedade \u00e9 maioritariamente interno.<\/p><p>A <a href=\"https:\/\/psicoresiliencia.com\/index.php\/psicoterapia-online\/areasdeintervencao\/ansiedade\/\">ansiedade<\/a> afeta a pessoa no seu todo, sendo uma rea\u00e7\u00e3o psicol\u00f3gica, comportamental e fisiol\u00f3gica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bd58f8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5bd58f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>N\u00edvel fisiol\u00f3gico &#8211;<\/strong> inclui rea\u00e7\u00f5es corporais, como o aumento do ritmo card\u00edaco, a tens\u00e3o muscular ou come\u00e7ar a suar mais.<\/p><p><strong>N\u00edvel comportamental &#8211;<\/strong> pode sabotar a sua capacidade de agir, de se expressar ou at\u00e9 de lidar com certas situa\u00e7\u00f5es.<\/p><p><strong>N\u00edvel psicol\u00f3gico &#8211;<\/strong> a ansiedade \u00e9 um estado subjetivo de apreens\u00e3o e inquieta\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb0ab29 elementor-widget elementor-widget-text-editor\" data-id=\"bb0ab29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ainda assim, a ansiedade \u00e9 uma parte inevit\u00e1vel da vida no mundo atual. \u00c9 importante compreender que h\u00e1 muitas situa\u00e7\u00f5es do dia-a-dia em que \u00e9 apropriado e razo\u00e1vel reagir com alguma ansiedade.<\/p><p>\u00a0<\/p><p>Ent\u00e3o, como \u00e9 que se distingue a ansiedade normal, do dia-a-dia, da ansiedade que \u00e9 um problema, isto \u00e9, da perturba\u00e7\u00e3o de ansiedade?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecebd16 elementor-widget elementor-widget-heading\" data-id=\"ecebd16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 Caracter\u00edsticas que distinguem ansiedade da perturba\u00e7\u00e3o de ansiedade:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe505da elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fe505da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><strong>\u00c9 mais intensa.<\/strong><\/li><li><strong>Persiste durante mais tempo <\/strong>(a ansiedade da perturba\u00e7\u00e3o de ansiedade pode persistir por meses, ou mais ainda, depois da situa\u00e7\u00e3o ter j\u00e1 passado)<\/li><li><strong>Interfere com o seu dia-a-dia, comprometendo-o.<\/strong><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A ansiedade \u00e9 uma parte inevit\u00e1vel da vida no mundo atual. Saiba mais sobre ansiedade e o que a distingue da perturba\u00e7\u00e3o de ansiedade.<\/p>\n","protected":false},"author":1,"featured_media":5147,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,53],"tags":[],"class_list":["post-5139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ansiedade","category-saude-mental"],"_links":{"self":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/posts\/5139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/comments?post=5139"}],"version-history":[{"count":0,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/posts\/5139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/media\/5147"}],"wp:attachment":[{"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/media?parent=5139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/categories?post=5139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/psicoresiliencia.com\/index.php\/wp-json\/wp\/v2\/tags?post=5139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}